{"id":22637,"date":"2022-01-07T08:24:04","date_gmt":"2022-01-07T07:24:04","guid":{"rendered":"https:\/\/clarityproject.de\/?post_type=product&#038;p=22637"},"modified":"2025-11-04T15:19:24","modified_gmt":"2025-11-04T14:19:24","slug":"seminaranzeige-clarityguide","status":"publish","type":"product","link":"https:\/\/clarityproject.de\/en\/product\/seminaranzeige-clarityguide\/","title":{"rendered":"Seminaranzeige ClarityGuide"},"content":{"rendered":"<p>Deine Anzeige wird auf www.clarityproject.de ver\u00f6ffentlicht und ist bis zum Kursbeginn sichtbar und buchbar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Anzeige wird auf www.clarityproject.de ver\u00f6ffentlicht und ist bis zum Kursbeginn sichtbar und buchbar.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[134],"product_tag":[],"class_list":{"0":"post-22637","1":"product","2":"type-product","3":"status-publish","5":"product_cat-clarityguides","6":"sales-flash-overlay","7":"woocommerce-text-align-center","8":"woocommerce-image-align-center","9":"do-quantity-buttons","11":"first","12":"instock","13":"virtual","14":"taxable","15":"purchasable","16":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/clarityproject.de\/en\/wp-json\/wp\/v2\/product\/22637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clarityproject.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/clarityproject.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/clarityproject.de\/en\/wp-json\/wp\/v2\/comments?post=22637"}],"wp:attachment":[{"href":"https:\/\/clarityproject.de\/en\/wp-json\/wp\/v2\/media?parent=22637"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/clarityproject.de\/en\/wp-json\/wp\/v2\/product_brand?post=22637"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/clarityproject.de\/en\/wp-json\/wp\/v2\/product_cat?post=22637"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/clarityproject.de\/en\/wp-json\/wp\/v2\/product_tag?post=22637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}